{"id":6987,"date":"2020-11-04T15:12:44","date_gmt":"2020-11-04T14:12:44","guid":{"rendered":"http:\/\/bierger.remich.lu\/?page_id=6987"},"modified":"2025-06-05T08:10:47","modified_gmt":"2025-06-05T06:10:47","slug":"abfallsammlungen","status":"publish","type":"page","link":"https:\/\/bierger.remich.lu\/en\/ville-de-remich\/umwelt\/francais-gestion-des-dechets\/abfallsammlungen\/","title":{"rendered":"Waste collections"},"content":{"rendered":"<h2>House-to-house collections:<\/h2>\n<ul>\n<li>Plastics (Valorlux)<\/li>\n<li>Paper<\/li>\n<li>Glass<\/li>\n<li>Household waste<\/li>\n<li>Organic waste<\/li>\n<li>Garden waste (April &#8211; early November)<\/li>\n<\/ul>\n<p>Garbage cans and locks for garbage cans and containers can be ordered from the citizens&#8217; office of the City of Remich by filling in a special form.<\/p>\n<p>A cleaning service for garbage cans and containers can be requested from the Lamesch company, which is also responsible for emptying the garbage cans.<\/p>\n<p>Further information can be found in our waste guide.<\/p>\n<h2>App &#8220;M\u00e4in Offall &#8211; Meng Ressourcen&#8221;<\/h2>\n<p>Thanks to the virtual pickup schedule, pickup reminders, and interactive map, all the information you need is at your fingertips.<\/p>\n<p>The app is available in four languages (Luxembourgish, French, German, and English). It can be downloaded for free from the App Store and Google Play.<\/p>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-17448 size-large\" src=\"https:\/\/bierger.remich.lu\/wp-content\/uploads\/sites\/3\/2025\/06\/Poster-A6-FR-72dpi-721x1024.jpg\" alt=\"\" width=\"721\" height=\"1024\" srcset=\"https:\/\/bierger.remich.lu\/wp-content\/uploads\/sites\/3\/2025\/06\/Poster-A6-FR-72dpi-721x1024.jpg 721w, https:\/\/bierger.remich.lu\/wp-content\/uploads\/sites\/3\/2025\/06\/Poster-A6-FR-72dpi-211x300.jpg 211w, https:\/\/bierger.remich.lu\/wp-content\/uploads\/sites\/3\/2025\/06\/Poster-A6-FR-72dpi.jpg 1165w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/>\n<p>&nbsp;","protected":false},"excerpt":{"rendered":"<p>House-to-house collections: Plastics (Valorlux) Paper Glass Household waste Organic waste Garden waste (April &#8211; early November) Garbage cans and locks for garbage cans and containers can be ordered from the citizens&#8217; office of the City of Remich by filling in a special form. A cleaning service for garbage cans and containers can be requested from&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/bierger.remich.lu\/en\/ville-de-remich\/umwelt\/francais-gestion-des-dechets\/abfallsammlungen\/\" title=\"ReadWaste collections\">Read more &raquo;<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"parent":1262,"menu_order":24,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"xn-wppe-expiration":[],"xn-wppe-expiration-action":[],"xn-wppe-expiration-prefix":[],"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-6987","page","type-page","status-publish","hentry","keyword-abfall","keyword-mulleimer","keyword-recyclage","keyword-valorlux"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Waste collections - Ville de Remich<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bierger.remich.lu\/ville-de-remich\/umwelt\/francais-gestion-des-dechets\/abfallsammlungen\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Waste collections - Ville de Remich\" \/>\n<meta property=\"og:description\" content=\"House-to-house collections: Plastics (Valorlux) Paper Glass Household waste Organic waste Garden waste (April &#8211; early November) Garbage cans and locks for garbage cans and containers can be ordered from the citizens&#8217; office of the City of Remich by filling in a special form. A cleaning service for garbage cans and containers can be requested from... Read more &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bierger.remich.lu\/ville-de-remich\/umwelt\/francais-gestion-des-dechets\/abfallsammlungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Ville de Remich\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-05T06:10:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bierger.remich.lu\/wp-content\/uploads\/sites\/3\/2025\/06\/Poster-A6-LU-72dpi.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bierger.remich.lu\\\/ville-de-remich\\\/umwelt\\\/francais-gestion-des-dechets\\\/abfallsammlungen\\\/\",\"url\":\"https:\\\/\\\/bierger.remich.lu\\\/ville-de-remich\\\/umwelt\\\/francais-gestion-des-dechets\\\/abfallsammlungen\\\/\",\"name\":\"Waste collections - Ville de Remich\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bierger.remich.lu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bierger.remich.lu\\\/ville-de-remich\\\/umwelt\\\/francais-gestion-des-dechets\\\/abfallsammlungen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bierger.remich.lu\\\/ville-de-remich\\\/umwelt\\\/francais-gestion-des-dechets\\\/abfallsammlungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bierger.remich.lu\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/06\\\/Poster-A6-LU-72dpi.jpg\",\"datePublished\":\"2020-11-04T14:12:44+00:00\",\"dateModified\":\"2025-06-05T06:10:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bierger.remich.lu\\\/ville-de-remich\\\/umwelt\\\/francais-gestion-des-dechets\\\/abfallsammlungen\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bierger.remich.lu\\\/ville-de-remich\\\/umwelt\\\/francais-gestion-des-dechets\\\/abfallsammlungen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/bierger.remich.lu\\\/ville-de-remich\\\/umwelt\\\/francais-gestion-des-dechets\\\/abfallsammlungen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bierger.remich.lu\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/06\\\/Poster-A6-LU-72dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/bierger.remich.lu\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/06\\\/Poster-A6-LU-72dpi.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bierger.remich.lu\\\/ville-de-remich\\\/umwelt\\\/francais-gestion-des-dechets\\\/abfallsammlungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/bierger.remich.lu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stadt Remich\",\"item\":\"https:\\\/\\\/bierger.remich.lu\\\/de\\\/ville-de-remich\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Umwelt\",\"item\":\"https:\\\/\\\/bierger.remich.lu\\\/de\\\/ville-de-remich\\\/umwelt\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Abfallentsorgung\",\"item\":\"https:\\\/\\\/bierger.remich.lu\\\/ville-de-remich\\\/umwelt\\\/francais-gestion-des-dechets\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Abfallsammlungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bierger.remich.lu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/bierger.remich.lu\\\/de\\\/\",\"name\":\"Ville de Remich\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bierger.remich.lu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Waste collections - Ville de Remich","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bierger.remich.lu\/ville-de-remich\/umwelt\/francais-gestion-des-dechets\/abfallsammlungen\/","og_locale":"en_GB","og_type":"article","og_title":"Waste collections - Ville de Remich","og_description":"House-to-house collections: Plastics (Valorlux) Paper Glass Household waste Organic waste Garden waste (April &#8211; early November) Garbage cans and locks for garbage cans and containers can be ordered from the citizens&#8217; office of the City of Remich by filling in a special form. A cleaning service for garbage cans and containers can be requested from... Read more &raquo;","og_url":"https:\/\/bierger.remich.lu\/ville-de-remich\/umwelt\/francais-gestion-des-dechets\/abfallsammlungen\/","og_site_name":"Ville de Remich","article_modified_time":"2025-06-05T06:10:47+00:00","og_image":[{"url":"https:\/\/bierger.remich.lu\/wp-content\/uploads\/sites\/3\/2025\/06\/Poster-A6-LU-72dpi.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bierger.remich.lu\/ville-de-remich\/umwelt\/francais-gestion-des-dechets\/abfallsammlungen\/","url":"https:\/\/bierger.remich.lu\/ville-de-remich\/umwelt\/francais-gestion-des-dechets\/abfallsammlungen\/","name":"Waste collections - Ville de Remich","isPartOf":{"@id":"https:\/\/bierger.remich.lu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bierger.remich.lu\/ville-de-remich\/umwelt\/francais-gestion-des-dechets\/abfallsammlungen\/#primaryimage"},"image":{"@id":"https:\/\/bierger.remich.lu\/ville-de-remich\/umwelt\/francais-gestion-des-dechets\/abfallsammlungen\/#primaryimage"},"thumbnailUrl":"https:\/\/bierger.remich.lu\/wp-content\/uploads\/sites\/3\/2025\/06\/Poster-A6-LU-72dpi.jpg","datePublished":"2020-11-04T14:12:44+00:00","dateModified":"2025-06-05T06:10:47+00:00","breadcrumb":{"@id":"https:\/\/bierger.remich.lu\/ville-de-remich\/umwelt\/francais-gestion-des-dechets\/abfallsammlungen\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bierger.remich.lu\/ville-de-remich\/umwelt\/francais-gestion-des-dechets\/abfallsammlungen\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/bierger.remich.lu\/ville-de-remich\/umwelt\/francais-gestion-des-dechets\/abfallsammlungen\/#primaryimage","url":"https:\/\/bierger.remich.lu\/wp-content\/uploads\/sites\/3\/2025\/06\/Poster-A6-LU-72dpi.jpg","contentUrl":"https:\/\/bierger.remich.lu\/wp-content\/uploads\/sites\/3\/2025\/06\/Poster-A6-LU-72dpi.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/bierger.remich.lu\/ville-de-remich\/umwelt\/francais-gestion-des-dechets\/abfallsammlungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/bierger.remich.lu\/de\/"},{"@type":"ListItem","position":2,"name":"Stadt Remich","item":"https:\/\/bierger.remich.lu\/de\/ville-de-remich\/"},{"@type":"ListItem","position":3,"name":"Umwelt","item":"https:\/\/bierger.remich.lu\/de\/ville-de-remich\/umwelt\/"},{"@type":"ListItem","position":4,"name":"Abfallentsorgung","item":"https:\/\/bierger.remich.lu\/ville-de-remich\/umwelt\/francais-gestion-des-dechets\/"},{"@type":"ListItem","position":5,"name":"Abfallsammlungen"}]},{"@type":"WebSite","@id":"https:\/\/bierger.remich.lu\/de\/#website","url":"https:\/\/bierger.remich.lu\/de\/","name":"Ville de Remich","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bierger.remich.lu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/bierger.remich.lu\/en\/wp-json\/wp\/v2\/pages\/6987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bierger.remich.lu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bierger.remich.lu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bierger.remich.lu\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bierger.remich.lu\/en\/wp-json\/wp\/v2\/comments?post=6987"}],"version-history":[{"count":6,"href":"https:\/\/bierger.remich.lu\/en\/wp-json\/wp\/v2\/pages\/6987\/revisions"}],"predecessor-version":[{"id":17451,"href":"https:\/\/bierger.remich.lu\/en\/wp-json\/wp\/v2\/pages\/6987\/revisions\/17451"}],"up":[{"embeddable":true,"href":"https:\/\/bierger.remich.lu\/en\/wp-json\/wp\/v2\/pages\/1262"}],"wp:attachment":[{"href":"https:\/\/bierger.remich.lu\/en\/wp-json\/wp\/v2\/media?parent=6987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}